{"id":24440,"date":"2017-10-23T00:00:00","date_gmt":"2017-10-23T00:00:00","guid":{"rendered":"http:\/\/localhost\/wisper_both\/shop\/uncategorized\/wisper-controller-ecn-00057\/"},"modified":"2026-04-20T21:25:23","modified_gmt":"2026-04-20T21:25:23","slug":"wisper-controller-ecn-00057","status":"publish","type":"product","link":"https:\/\/wisperbikes.com\/nl\/shop\/electronic\/wisper-controller-ecn-00057\/","title":{"rendered":"Wisper Controller Ecn 00057"},"content":{"rendered":"<p>WISPER RANGE 2009-2015<\/p>\n<p>SKU: PWX312110<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WISPER RANGE 2009-2015 SKU: PWX312110<\/p>\n","protected":false},"featured_media":23091,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[169],"product_tag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wisper Controller Ecn 00057 | Fietsaccessoires<\/title>\n<meta name=\"description\" content=\"De Wisper Controller Ecn 00057 is een eersteklas e-bike controller, een uitstekende keuze voor iedereen die op zoek is naar een hoogwaardige optie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wisperbikes.com\/nl\/shop\/electronic\/wisper-controller-ecn-00057\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wisper Controller Ecn 00057 | Fietsaccessoires\" \/>\n<meta property=\"og:description\" content=\"De Wisper Controller Ecn 00057 is een eersteklas e-bike controller, een uitstekende keuze voor iedereen die op zoek is naar een hoogwaardige optie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wisperbikes.com\/nl\/shop\/electronic\/wisper-controller-ecn-00057\/\" \/>\n<meta property=\"og:site_name\" content=\"Wisper Bikes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amps.Bike\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-20T21:25:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wisperbikes.com\/nl\/wp-content\/uploads\/2020\/09\/PWX312110-WISPER-WISPER-CONTROLLER-ECN-00057-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"970\" \/>\n\t<meta property=\"og:image:height\" content=\"970\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@wisperebikes\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wisperbikes.com\/nl\/shop\/electronic\/wisper-controller-ecn-00057\/\",\"url\":\"https:\/\/wisperbikes.com\/nl\/shop\/electronic\/wisper-controller-ecn-00057\/\",\"name\":\"Wisper Controller Ecn 00057 | Fietsaccessoires\",\"isPartOf\":{\"@id\":\"https:\/\/wisperbikes.com\/nl\/#website\"},\"datePublished\":\"2017-10-23T00:00:00+00:00\",\"dateModified\":\"2026-04-20T21:25:23+00:00\",\"description\":\"De Wisper Controller Ecn 00057 is een eersteklas e-bike controller, een uitstekende keuze voor iedereen die op zoek is naar een hoogwaardige optie.\",\"breadcrumb\":{\"@id\":\"https:\/\/wisperbikes.com\/nl\/shop\/electronic\/wisper-controller-ecn-00057\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wisperbikes.com\/nl\/shop\/electronic\/wisper-controller-ecn-00057\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wisperbikes.com\/nl\/shop\/electronic\/wisper-controller-ecn-00057\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/wisperbikes.com\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Our Shop\",\"item\":\"https:\/\/wisperbikes.com\/nl\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wisper Controller Ecn 00057\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wisperbikes.com\/nl\/#website\",\"url\":\"https:\/\/wisperbikes.com\/nl\/\",\"name\":\"Wisper Bikes\",\"description\":\"Electric Bikes\",\"publisher\":{\"@id\":\"https:\/\/wisperbikes.com\/nl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wisperbikes.com\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/wisperbikes.com\/nl\/#organization\",\"name\":\"Wisper Electric Bikes\",\"alternateName\":\"Wisper E-Bikes\",\"url\":\"https:\/\/wisperbikes.com\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/wisperbikes.com\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/wisperbikes.com\/nl\/wp-content\/uploads\/2021\/06\/WISPER-Logo.png\",\"contentUrl\":\"https:\/\/wisperbikes.com\/nl\/wp-content\/uploads\/2021\/06\/WISPER-Logo.png\",\"width\":250,\"height\":65,\"caption\":\"Wisper Electric Bikes\"},\"image\":{\"@id\":\"https:\/\/wisperbikes.com\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Amps.Bike\/\",\"https:\/\/twitter.com\/wisperebikes\",\"https:\/\/www.instagram.com\/wisperbikes\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wisper Controller Ecn 00057 | Fietsaccessoires","description":"De Wisper Controller Ecn 00057 is een eersteklas e-bike controller, een uitstekende keuze voor iedereen die op zoek is naar een hoogwaardige optie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wisperbikes.com\/nl\/shop\/electronic\/wisper-controller-ecn-00057\/","og_locale":"nl_NL","og_type":"article","og_title":"Wisper Controller Ecn 00057 | Fietsaccessoires","og_description":"De Wisper Controller Ecn 00057 is een eersteklas e-bike controller, een uitstekende keuze voor iedereen die op zoek is naar een hoogwaardige optie.","og_url":"https:\/\/wisperbikes.com\/nl\/shop\/electronic\/wisper-controller-ecn-00057\/","og_site_name":"Wisper Bikes","article_publisher":"https:\/\/www.facebook.com\/Amps.Bike\/","article_modified_time":"2026-04-20T21:25:23+00:00","og_image":[{"width":970,"height":970,"url":"https:\/\/wisperbikes.com\/nl\/wp-content\/uploads\/2020\/09\/PWX312110-WISPER-WISPER-CONTROLLER-ECN-00057-1-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@wisperebikes","twitter_misc":{"Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wisperbikes.com\/nl\/shop\/electronic\/wisper-controller-ecn-00057\/","url":"https:\/\/wisperbikes.com\/nl\/shop\/electronic\/wisper-controller-ecn-00057\/","name":"Wisper Controller Ecn 00057 | Fietsaccessoires","isPartOf":{"@id":"https:\/\/wisperbikes.com\/nl\/#website"},"datePublished":"2017-10-23T00:00:00+00:00","dateModified":"2026-04-20T21:25:23+00:00","description":"De Wisper Controller Ecn 00057 is een eersteklas e-bike controller, een uitstekende keuze voor iedereen die op zoek is naar een hoogwaardige optie.","breadcrumb":{"@id":"https:\/\/wisperbikes.com\/nl\/shop\/electronic\/wisper-controller-ecn-00057\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wisperbikes.com\/nl\/shop\/electronic\/wisper-controller-ecn-00057\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wisperbikes.com\/nl\/shop\/electronic\/wisper-controller-ecn-00057\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wisperbikes.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Our Shop","item":"https:\/\/wisperbikes.com\/nl\/shop\/"},{"@type":"ListItem","position":3,"name":"Wisper Controller Ecn 00057"}]},{"@type":"WebSite","@id":"https:\/\/wisperbikes.com\/nl\/#website","url":"https:\/\/wisperbikes.com\/nl\/","name":"Wisper Bikes","description":"Electric Bikes","publisher":{"@id":"https:\/\/wisperbikes.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wisperbikes.com\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/wisperbikes.com\/nl\/#organization","name":"Wisper Electric Bikes","alternateName":"Wisper E-Bikes","url":"https:\/\/wisperbikes.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/wisperbikes.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/wisperbikes.com\/nl\/wp-content\/uploads\/2021\/06\/WISPER-Logo.png","contentUrl":"https:\/\/wisperbikes.com\/nl\/wp-content\/uploads\/2021\/06\/WISPER-Logo.png","width":250,"height":65,"caption":"Wisper Electric Bikes"},"image":{"@id":"https:\/\/wisperbikes.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amps.Bike\/","https:\/\/twitter.com\/wisperebikes","https:\/\/www.instagram.com\/wisperbikes\/"]}]}},"_links":{"self":[{"href":"https:\/\/wisperbikes.com\/nl\/wp-json\/wp\/v2\/product\/24440"}],"collection":[{"href":"https:\/\/wisperbikes.com\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/wisperbikes.com\/nl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/wisperbikes.com\/nl\/wp-json\/wp\/v2\/comments?post=24440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wisperbikes.com\/nl\/wp-json\/wp\/v2\/media\/23091"}],"wp:attachment":[{"href":"https:\/\/wisperbikes.com\/nl\/wp-json\/wp\/v2\/media?parent=24440"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/wisperbikes.com\/nl\/wp-json\/wp\/v2\/product_cat?post=24440"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/wisperbikes.com\/nl\/wp-json\/wp\/v2\/product_tag?post=24440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}